{"id":9644,"date":"2020-02-17T19:02:41","date_gmt":"2020-02-17T19:02:41","guid":{"rendered":"https:\/\/xenum.com\/?page_id=9644"},"modified":"2023-09-11T08:26:57","modified_gmt":"2023-09-11T07:26:57","slug":"semix-0w30","status":"publish","type":"page","link":"https:\/\/xenum.com\/nl\/startpagina\/producten\/olien\/motor\/hybride-synthetisch\/semix-0w30\/","title":{"rendered":"SEMIX 0W30"},"content":{"rendered":"<p>SEMIX 0W30 is een hybride synthetische motorolie die speciaal werd samengesteld voor gebruik in benzine- en dieselmotoren van personenauto's en bestelwagens, met of zonder turbocompressor. Deze veelzijdige olie biedt uitstekende bescherming tegen slijtage, verbetert de brandstofeffici\u00ebntie en kan het hele jaar door gebruikt worden, zelfs bij extreem koude temperaturen.<\/p>\n<h3><strong>Eigenschappen<\/strong><\/h3>\n<ul>\n<li>Biedt uitstekende bescherming tegen wrijving en slijtage, zelfs bij extreem lage temperaturen<\/li>\n<li>Verbetert de brandstofeffici\u00ebntie<\/li>\n<li>Verlaagt CO\u2082-uitstoot<\/li>\n<li>Verbetert prestaties tijdens koude start<\/li>\n<li>Heeft een sterk detergerend vermogen om motorafzettingen te voorkomen<\/li>\n<li>Biedt hoge weerstand tegen afschuiving (shearing)<\/li>\n<li>Behoudt een lage en stabiele viscositeitsindex<\/li>\n<li>Vertoont uitzonderlijke vloeibaarheid, zelfs bij lage temperaturen<\/li>\n<\/ul>\n<h3><strong>Toepassing<\/strong><\/h3>\n<p>Ontworpen voor gebruik in diesel- en benzinemotoren van personenwagens in de BMW-groep. Ook geschikt voor andere OEM-diesel- en benzinemotoren die een LOW SAPS-olie met een viscositeit van 0W30 vereisen.<\/p>\n<h3><strong>Specificaties<\/strong><\/h3>\n<ul>\n<li>ACEA A3\/B4<\/li>\n<li>API SH\/CF<\/li>\n<li>BMW Longlife-01<\/li>\n<li>MB 229.3\/226.5<\/li>\n<li>Renault RN 0700<\/li>\n<li>VW 502.00\/505.00<\/li>\n<li>API SN\/CF (API SN-kwaliteit: niet-licentieerbaar vanwege fosforlimiet)<\/li>\n<\/ul>\n<h4 class=\"TDSSection\"><strong>Verkrijgbaar in:<br \/>\n<\/strong><\/h4>\n<div id=\"the-product-details\" class=\"ct-div-block\">\n<div id=\"text_block-25-15726\" class=\"ct-text-block\">\n<p>1L - REF.2379001A<br \/>\n12 X 1L KARTON<\/p>\n<p>4L - REF. 2362004A<br \/>\n4 X 4L KARTON<\/p>\n<p>5L - REF. 2355005A<br \/>\n4 X 5L KARTON<\/p>\n<p>20L, 60L, 208L<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SEMIX 0W30 is een hybride synthetische motorolie die speciaal werd samengesteld voor gebruik in benzine- en dieselmotoren van personenauto's en bestelwagens, met of zonder turbocompressor. Deze veelzijdige olie biedt uitstekende bescherming tegen slijtage, verbetert de brandstofeffici\u00ebntie en kan het hele jaar door gebruikt worden, zelfs bij extreem koude temperaturen. Eigenschappen Biedt uitstekende bescherming tegen wrijving [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9630,"parent":9601,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"product-page.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-9644","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/pages\/9644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/comments?post=9644"}],"version-history":[{"count":6,"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/pages\/9644\/revisions"}],"predecessor-version":[{"id":24314,"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/pages\/9644\/revisions\/24314"}],"up":[{"embeddable":true,"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/pages\/9601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/media\/9630"}],"wp:attachment":[{"href":"https:\/\/xenum.com\/nl\/wp-json\/wp\/v2\/media?parent=9644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}